{"id":13559,"count":152,"description":"<p>30+ documents to take back control in situations of overdue payments and contractual disagreements.<\/p>","link":"https:\/\/zegal.com\/en-nz\/template\/debts-and-disputes\/","name":"Debts and Disputes","slug":"debts-and-disputes","taxonomy":"template","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Debts and Disputes Archives | Zegal New Zealand<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Debts and Disputes Archives\" \/>\n<meta property=\"og:description\" content=\"30+ documents to take back control in situations of overdue payments and contractual disagreements.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zegal.com\/en-nz\/template\/debts-and-disputes\/\" \/>\n<meta property=\"og:site_name\" content=\"Zegal New Zealand\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zegal.com\/wp-content\/uploads\/2023\/09\/zegal-logo-red.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@getzegal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/template\\\/debts-and-disputes\\\/\",\"url\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/template\\\/debts-and-disputes\\\/\",\"name\":\"Debts and Disputes Archives | Zegal New Zealand\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/template\\\/debts-and-disputes\\\/#breadcrumb\"},\"inLanguage\":\"en-NZ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/template\\\/debts-and-disputes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Legal Templates\",\"item\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/all-docs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Debts and Disputes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/#website\",\"url\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/\",\"name\":\"Zegal New Zealand\",\"description\":\"Need legal? Click Zegal.\",\"publisher\":{\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-NZ\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/#organization\",\"name\":\"Zegal New Zealand\",\"url\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-NZ\",\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zegal.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/zegal-logo-white.png\",\"contentUrl\":\"https:\\\/\\\/zegal.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/zegal-logo-white.png\",\"width\":200,\"height\":69,\"caption\":\"Zegal New Zealand\"},\"image\":{\"@id\":\"https:\\\/\\\/zegal.com\\\/en-nz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/getzegal\\\/\",\"https:\\\/\\\/x.com\\\/getzegal\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/getzegal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@legalzegal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Debts and Disputes Archives | Zegal New Zealand","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Debts and Disputes Archives","og_description":"30+ documents to take back control in situations of overdue payments and contractual disagreements.","og_url":"https:\/\/zegal.com\/en-nz\/template\/debts-and-disputes\/","og_site_name":"Zegal New Zealand","og_image":[{"width":1200,"height":627,"url":"https:\/\/zegal.com\/wp-content\/uploads\/2023\/09\/zegal-logo-red.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@getzegal","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zegal.com\/en-nz\/template\/debts-and-disputes\/","url":"https:\/\/zegal.com\/en-nz\/template\/debts-and-disputes\/","name":"Debts and Disputes Archives | Zegal New Zealand","isPartOf":{"@id":"https:\/\/zegal.com\/en-nz\/#website"},"breadcrumb":{"@id":"https:\/\/zegal.com\/en-nz\/template\/debts-and-disputes\/#breadcrumb"},"inLanguage":"en-NZ"},{"@type":"BreadcrumbList","@id":"https:\/\/zegal.com\/en-nz\/template\/debts-and-disputes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Legal Templates","item":"https:\/\/zegal.com\/en-nz\/all-docs\/"},{"@type":"ListItem","position":2,"name":"Debts and Disputes"}]},{"@type":"WebSite","@id":"https:\/\/zegal.com\/en-nz\/#website","url":"https:\/\/zegal.com\/en-nz\/","name":"Zegal New Zealand","description":"Need legal? Click Zegal.","publisher":{"@id":"https:\/\/zegal.com\/en-nz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zegal.com\/en-nz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-NZ"},{"@type":"Organization","@id":"https:\/\/zegal.com\/en-nz\/#organization","name":"Zegal New Zealand","url":"https:\/\/zegal.com\/en-nz\/","logo":{"@type":"ImageObject","inLanguage":"en-NZ","@id":"https:\/\/zegal.com\/en-nz\/#\/schema\/logo\/image\/","url":"https:\/\/zegal.com\/wp-content\/uploads\/2021\/11\/zegal-logo-white.png","contentUrl":"https:\/\/zegal.com\/wp-content\/uploads\/2021\/11\/zegal-logo-white.png","width":200,"height":69,"caption":"Zegal New Zealand"},"image":{"@id":"https:\/\/zegal.com\/en-nz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/getzegal\/","https:\/\/x.com\/getzegal","https:\/\/www.linkedin.com\/company\/getzegal\/","https:\/\/www.youtube.com\/@legalzegal"]}]}},"_links":{"self":[{"href":"https:\/\/zegal.com\/en-nz\/wp-json\/wp\/v2\/template\/13559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zegal.com\/en-nz\/wp-json\/wp\/v2\/template"}],"about":[{"href":"https:\/\/zegal.com\/en-nz\/wp-json\/wp\/v2\/taxonomies\/template"}],"wp:post_type":[{"href":"https:\/\/zegal.com\/en-nz\/wp-json\/wp\/v2\/pages?template=13559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}